{"id":13011,"date":"2025-07-13T10:10:00","date_gmt":"2025-07-13T01:10:00","guid":{"rendered":"https:\/\/sentech.co.jp\/products\/stc-glb16ku35dcxp124-m72"},"modified":"2026-05-20T00:52:38","modified_gmt":"2026-05-19T15:52:38","slug":"stc-glb16ku35dcxp124-m72","status":"publish","type":"products","link":"https:\/\/sentech.co.jp\/en\/products\/stc-glb16ku35dcxp124-m72","title":{"rendered":"STC-GLB16KU35DCXP124-M72"},"featured_media":14656,"menu_order":69,"template":"","products_cate":[296],"products_cate_interface":[182],"class_list":["post-13011","products","type-products","status-publish","has-post-thumbnail","hentry","products_cate-line-coaxpress","products_cate_interface-coaxpress-cxp-12"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>STC-GLB16KU35DCXP124-M72 | OMRON SENTECH CO., LTD.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sentech.co.jp\/en\/products\/stc-glb16ku35dcxp124-m72\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"STC-GLB16KU35DCXP124-M72 | OMRON SENTECH CO., LTD.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sentech.co.jp\/en\/products\/stc-glb16ku35dcxp124-m72\" \/>\n<meta property=\"og:site_name\" content=\"OMRON SENTECH CO., LTD.\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-19T15:52:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sentech.co.jp\/wp-content\/uploads\/2025\/09\/ogp.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sentech.co.jp\\\/en\\\/products\\\/stc-glb16ku35dcxp124-m72\",\"url\":\"https:\\\/\\\/sentech.co.jp\\\/en\\\/products\\\/stc-glb16ku35dcxp124-m72\",\"name\":\"STC-GLB16KU35DCXP124-M72 | OMRON SENTECH CO., LTD.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sentech.co.jp\\\/en#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/sentech.co.jp\\\/en\\\/products\\\/stc-glb16ku35dcxp124-m72#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/sentech.co.jp\\\/en\\\/products\\\/stc-glb16ku35dcxp124-m72#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sentech.co.jp\\\/wp-content\\\/uploads\\\/2026\\\/08\\\/STC-GLB16KU35DCXP124-M72_01.jpg\",\"datePublished\":\"2025-07-13T01:10:00+00:00\",\"dateModified\":\"2026-05-19T15:52:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sentech.co.jp\\\/en\\\/products\\\/stc-glb16ku35dcxp124-m72#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sentech.co.jp\\\/en\\\/products\\\/stc-glb16ku35dcxp124-m72\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/sentech.co.jp\\\/en\\\/products\\\/stc-glb16ku35dcxp124-m72#primaryimage\",\"url\":\"https:\\\/\\\/sentech.co.jp\\\/wp-content\\\/uploads\\\/2026\\\/08\\\/STC-GLB16KU35DCXP124-M72_01.jpg\",\"contentUrl\":\"https:\\\/\\\/sentech.co.jp\\\/wp-content\\\/uploads\\\/2026\\\/08\\\/STC-GLB16KU35DCXP124-M72_01.jpg\",\"width\":250,\"height\":167},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sentech.co.jp\\\/en\\\/products\\\/stc-glb16ku35dcxp124-m72#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u30db\u30fc\u30e0\",\"item\":\"https:\\\/\\\/sentech.co.jp\\\/en\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u88fd\u54c1\u60c5\u5831\",\"item\":\"https:\\\/\\\/sentech.co.jp\\\/en\\\/products\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"STC-GLB16KU35DCXP124-M72\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sentech.co.jp\\\/en#website\",\"url\":\"https:\\\/\\\/sentech.co.jp\\\/en\",\"name\":\"\u30aa\u30e0\u30ed\u30f3\u30bb\u30f3\u30c6\u30c3\u30af\u682a\u5f0f\u4f1a\u793e\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/sentech.co.jp\\\/en#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sentech.co.jp\\\/en?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/sentech.co.jp\\\/en#organization\",\"name\":\"\u30aa\u30e0\u30ed\u30f3\u30bb\u30f3\u30c6\u30c3\u30af\u682a\u5f0f\u4f1a\u793e\",\"url\":\"https:\\\/\\\/sentech.co.jp\\\/en\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/sentech.co.jp\\\/en#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/sentech.co.jp\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/ogp.png\",\"contentUrl\":\"https:\\\/\\\/sentech.co.jp\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/ogp.png\",\"width\":1200,\"height\":630,\"caption\":\"\u30aa\u30e0\u30ed\u30f3\u30bb\u30f3\u30c6\u30c3\u30af\u682a\u5f0f\u4f1a\u793e\"},\"image\":{\"@id\":\"https:\\\/\\\/sentech.co.jp\\\/en#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"STC-GLB16KU35DCXP124-M72 | OMRON SENTECH CO., LTD.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sentech.co.jp\/en\/products\/stc-glb16ku35dcxp124-m72","og_locale":"en_US","og_type":"article","og_title":"STC-GLB16KU35DCXP124-M72 | OMRON SENTECH CO., LTD.","og_url":"https:\/\/sentech.co.jp\/en\/products\/stc-glb16ku35dcxp124-m72","og_site_name":"OMRON SENTECH CO., LTD.","article_modified_time":"2026-05-19T15:52:38+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/sentech.co.jp\/wp-content\/uploads\/2025\/09\/ogp.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/sentech.co.jp\/en\/products\/stc-glb16ku35dcxp124-m72","url":"https:\/\/sentech.co.jp\/en\/products\/stc-glb16ku35dcxp124-m72","name":"STC-GLB16KU35DCXP124-M72 | OMRON SENTECH CO., LTD.","isPartOf":{"@id":"https:\/\/sentech.co.jp\/en#website"},"primaryImageOfPage":{"@id":"https:\/\/sentech.co.jp\/en\/products\/stc-glb16ku35dcxp124-m72#primaryimage"},"image":{"@id":"https:\/\/sentech.co.jp\/en\/products\/stc-glb16ku35dcxp124-m72#primaryimage"},"thumbnailUrl":"https:\/\/sentech.co.jp\/wp-content\/uploads\/2026\/08\/STC-GLB16KU35DCXP124-M72_01.jpg","datePublished":"2025-07-13T01:10:00+00:00","dateModified":"2026-05-19T15:52:38+00:00","breadcrumb":{"@id":"https:\/\/sentech.co.jp\/en\/products\/stc-glb16ku35dcxp124-m72#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sentech.co.jp\/en\/products\/stc-glb16ku35dcxp124-m72"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/sentech.co.jp\/en\/products\/stc-glb16ku35dcxp124-m72#primaryimage","url":"https:\/\/sentech.co.jp\/wp-content\/uploads\/2026\/08\/STC-GLB16KU35DCXP124-M72_01.jpg","contentUrl":"https:\/\/sentech.co.jp\/wp-content\/uploads\/2026\/08\/STC-GLB16KU35DCXP124-M72_01.jpg","width":250,"height":167},{"@type":"BreadcrumbList","@id":"https:\/\/sentech.co.jp\/en\/products\/stc-glb16ku35dcxp124-m72#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u30db\u30fc\u30e0","item":"https:\/\/sentech.co.jp\/en"},{"@type":"ListItem","position":2,"name":"\u88fd\u54c1\u60c5\u5831","item":"https:\/\/sentech.co.jp\/en\/products"},{"@type":"ListItem","position":3,"name":"STC-GLB16KU35DCXP124-M72"}]},{"@type":"WebSite","@id":"https:\/\/sentech.co.jp\/en#website","url":"https:\/\/sentech.co.jp\/en","name":"\u30aa\u30e0\u30ed\u30f3\u30bb\u30f3\u30c6\u30c3\u30af\u682a\u5f0f\u4f1a\u793e","description":"","publisher":{"@id":"https:\/\/sentech.co.jp\/en#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sentech.co.jp\/en?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/sentech.co.jp\/en#organization","name":"\u30aa\u30e0\u30ed\u30f3\u30bb\u30f3\u30c6\u30c3\u30af\u682a\u5f0f\u4f1a\u793e","url":"https:\/\/sentech.co.jp\/en","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/sentech.co.jp\/en#\/schema\/logo\/image\/","url":"https:\/\/sentech.co.jp\/wp-content\/uploads\/2025\/09\/ogp.png","contentUrl":"https:\/\/sentech.co.jp\/wp-content\/uploads\/2025\/09\/ogp.png","width":1200,"height":630,"caption":"\u30aa\u30e0\u30ed\u30f3\u30bb\u30f3\u30c6\u30c3\u30af\u682a\u5f0f\u4f1a\u793e"},"image":{"@id":"https:\/\/sentech.co.jp\/en#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/sentech.co.jp\/en\/wp-json\/wp\/v2\/products\/13011","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sentech.co.jp\/en\/wp-json\/wp\/v2\/products"}],"about":[{"href":"https:\/\/sentech.co.jp\/en\/wp-json\/wp\/v2\/types\/products"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sentech.co.jp\/en\/wp-json\/wp\/v2\/media\/14656"}],"wp:attachment":[{"href":"https:\/\/sentech.co.jp\/en\/wp-json\/wp\/v2\/media?parent=13011"}],"wp:term":[{"taxonomy":"products_cate","embeddable":true,"href":"https:\/\/sentech.co.jp\/en\/wp-json\/wp\/v2\/products_cate?post=13011"},{"taxonomy":"products_cate_interface","embeddable":true,"href":"https:\/\/sentech.co.jp\/en\/wp-json\/wp\/v2\/products_cate_interface?post=13011"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}