{"id":9598,"date":"2021-10-04T11:10:00","date_gmt":"2021-10-04T02:10:00","guid":{"rendered":"https:\/\/sentech.co.jp\/products\/stc-bbs500ge-bc"},"modified":"2026-05-30T23:49:40","modified_gmt":"2026-05-30T14:49:40","slug":"stc-bbs500ge-bc","status":"publish","type":"products","link":"https:\/\/sentech.co.jp\/en\/products\/stc-bbs500ge-bc","title":{"rendered":"STC-BBS500GE-BC"},"featured_media":6810,"menu_order":198,"template":"","products_cate":[195],"products_cate_interface":[185],"class_list":["post-9598","products","type-products","status-publish","has-post-thumbnail","hentry","products_cate-gige-board-areacamera","products_cate_interface-gige-vision"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>STC-BBS500GE-BC | OMRON SENTECH CO., LTD.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sentech.co.jp\/en\/products\/stc-bbs500ge-bc\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"STC-BBS500GE-BC | OMRON SENTECH CO., LTD.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sentech.co.jp\/en\/products\/stc-bbs500ge-bc\" \/>\n<meta property=\"og:site_name\" content=\"OMRON SENTECH CO., LTD.\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-30T14:49:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sentech.co.jp\/wp-content\/uploads\/2025\/07\/STC-BBS500GE-BC_01.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"342\" \/>\n\t<meta property=\"og:image:height\" content=\"151\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sentech.co.jp\\\/en\\\/products\\\/stc-bbs500ge-bc\",\"url\":\"https:\\\/\\\/sentech.co.jp\\\/en\\\/products\\\/stc-bbs500ge-bc\",\"name\":\"STC-BBS500GE-BC | OMRON SENTECH CO., LTD.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sentech.co.jp\\\/en#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/sentech.co.jp\\\/en\\\/products\\\/stc-bbs500ge-bc#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/sentech.co.jp\\\/en\\\/products\\\/stc-bbs500ge-bc#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sentech.co.jp\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/STC-BBS500GE-BC_01.jpg\",\"datePublished\":\"2021-10-04T02:10:00+00:00\",\"dateModified\":\"2026-05-30T14:49:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sentech.co.jp\\\/en\\\/products\\\/stc-bbs500ge-bc#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sentech.co.jp\\\/en\\\/products\\\/stc-bbs500ge-bc\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/sentech.co.jp\\\/en\\\/products\\\/stc-bbs500ge-bc#primaryimage\",\"url\":\"https:\\\/\\\/sentech.co.jp\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/STC-BBS500GE-BC_01.jpg\",\"contentUrl\":\"https:\\\/\\\/sentech.co.jp\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/STC-BBS500GE-BC_01.jpg\",\"width\":342,\"height\":151},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sentech.co.jp\\\/en\\\/products\\\/stc-bbs500ge-bc#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u30db\u30fc\u30e0\",\"item\":\"https:\\\/\\\/sentech.co.jp\\\/en\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u88fd\u54c1\u60c5\u5831\",\"item\":\"https:\\\/\\\/sentech.co.jp\\\/en\\\/products\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"STC-BBS500GE-BC\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sentech.co.jp\\\/en#website\",\"url\":\"https:\\\/\\\/sentech.co.jp\\\/en\",\"name\":\"\u30aa\u30e0\u30ed\u30f3\u30bb\u30f3\u30c6\u30c3\u30af\u682a\u5f0f\u4f1a\u793e\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/sentech.co.jp\\\/en#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sentech.co.jp\\\/en?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/sentech.co.jp\\\/en#organization\",\"name\":\"\u30aa\u30e0\u30ed\u30f3\u30bb\u30f3\u30c6\u30c3\u30af\u682a\u5f0f\u4f1a\u793e\",\"url\":\"https:\\\/\\\/sentech.co.jp\\\/en\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/sentech.co.jp\\\/en#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/sentech.co.jp\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/ogp.png\",\"contentUrl\":\"https:\\\/\\\/sentech.co.jp\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/ogp.png\",\"width\":1200,\"height\":630,\"caption\":\"\u30aa\u30e0\u30ed\u30f3\u30bb\u30f3\u30c6\u30c3\u30af\u682a\u5f0f\u4f1a\u793e\"},\"image\":{\"@id\":\"https:\\\/\\\/sentech.co.jp\\\/en#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"STC-BBS500GE-BC | OMRON SENTECH CO., LTD.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sentech.co.jp\/en\/products\/stc-bbs500ge-bc","og_locale":"en_US","og_type":"article","og_title":"STC-BBS500GE-BC | OMRON SENTECH CO., LTD.","og_url":"https:\/\/sentech.co.jp\/en\/products\/stc-bbs500ge-bc","og_site_name":"OMRON SENTECH CO., LTD.","article_modified_time":"2026-05-30T14:49:40+00:00","og_image":[{"width":342,"height":151,"url":"https:\/\/sentech.co.jp\/wp-content\/uploads\/2025\/07\/STC-BBS500GE-BC_01.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/sentech.co.jp\/en\/products\/stc-bbs500ge-bc","url":"https:\/\/sentech.co.jp\/en\/products\/stc-bbs500ge-bc","name":"STC-BBS500GE-BC | OMRON SENTECH CO., LTD.","isPartOf":{"@id":"https:\/\/sentech.co.jp\/en#website"},"primaryImageOfPage":{"@id":"https:\/\/sentech.co.jp\/en\/products\/stc-bbs500ge-bc#primaryimage"},"image":{"@id":"https:\/\/sentech.co.jp\/en\/products\/stc-bbs500ge-bc#primaryimage"},"thumbnailUrl":"https:\/\/sentech.co.jp\/wp-content\/uploads\/2025\/07\/STC-BBS500GE-BC_01.jpg","datePublished":"2021-10-04T02:10:00+00:00","dateModified":"2026-05-30T14:49:40+00:00","breadcrumb":{"@id":"https:\/\/sentech.co.jp\/en\/products\/stc-bbs500ge-bc#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sentech.co.jp\/en\/products\/stc-bbs500ge-bc"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/sentech.co.jp\/en\/products\/stc-bbs500ge-bc#primaryimage","url":"https:\/\/sentech.co.jp\/wp-content\/uploads\/2025\/07\/STC-BBS500GE-BC_01.jpg","contentUrl":"https:\/\/sentech.co.jp\/wp-content\/uploads\/2025\/07\/STC-BBS500GE-BC_01.jpg","width":342,"height":151},{"@type":"BreadcrumbList","@id":"https:\/\/sentech.co.jp\/en\/products\/stc-bbs500ge-bc#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u30db\u30fc\u30e0","item":"https:\/\/sentech.co.jp\/en"},{"@type":"ListItem","position":2,"name":"\u88fd\u54c1\u60c5\u5831","item":"https:\/\/sentech.co.jp\/en\/products"},{"@type":"ListItem","position":3,"name":"STC-BBS500GE-BC"}]},{"@type":"WebSite","@id":"https:\/\/sentech.co.jp\/en#website","url":"https:\/\/sentech.co.jp\/en","name":"\u30aa\u30e0\u30ed\u30f3\u30bb\u30f3\u30c6\u30c3\u30af\u682a\u5f0f\u4f1a\u793e","description":"","publisher":{"@id":"https:\/\/sentech.co.jp\/en#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sentech.co.jp\/en?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/sentech.co.jp\/en#organization","name":"\u30aa\u30e0\u30ed\u30f3\u30bb\u30f3\u30c6\u30c3\u30af\u682a\u5f0f\u4f1a\u793e","url":"https:\/\/sentech.co.jp\/en","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/sentech.co.jp\/en#\/schema\/logo\/image\/","url":"https:\/\/sentech.co.jp\/wp-content\/uploads\/2025\/09\/ogp.png","contentUrl":"https:\/\/sentech.co.jp\/wp-content\/uploads\/2025\/09\/ogp.png","width":1200,"height":630,"caption":"\u30aa\u30e0\u30ed\u30f3\u30bb\u30f3\u30c6\u30c3\u30af\u682a\u5f0f\u4f1a\u793e"},"image":{"@id":"https:\/\/sentech.co.jp\/en#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/sentech.co.jp\/en\/wp-json\/wp\/v2\/products\/9598","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sentech.co.jp\/en\/wp-json\/wp\/v2\/products"}],"about":[{"href":"https:\/\/sentech.co.jp\/en\/wp-json\/wp\/v2\/types\/products"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sentech.co.jp\/en\/wp-json\/wp\/v2\/media\/6810"}],"wp:attachment":[{"href":"https:\/\/sentech.co.jp\/en\/wp-json\/wp\/v2\/media?parent=9598"}],"wp:term":[{"taxonomy":"products_cate","embeddable":true,"href":"https:\/\/sentech.co.jp\/en\/wp-json\/wp\/v2\/products_cate?post=9598"},{"taxonomy":"products_cate_interface","embeddable":true,"href":"https:\/\/sentech.co.jp\/en\/wp-json\/wp\/v2\/products_cate_interface?post=9598"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}